{"id":51,"count":9,"description":"<h3>SCOREBOARD MANUAL AND ELETTRONIC, BOCCE COURT COUNTER<\/h3>\r\nHere different manual scoreboard or elettronic scoreboard for bocce court. Money timer counter avaiable, different model on this store","link":"https:\/\/colleonibocce.com\/en\/product-category\/scoreboard-and-timer-counters\/","name":"Scoreboard and timer counters","slug":"scoreboard-and-timer-counters","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segnapunti elettronici e tariffatori per campi da bocce - Colleoni bocce<\/title>\n<meta name=\"description\" content=\"I migliori segnapunti elettronici e tariffatori per campi da bocce. Indispensabili per diputare gare e tornei. Necessari per contabilizzare le ore di gioco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segnapunti elettronici e tariffatori per campi da bocce - Colleoni bocce\" \/>\n<meta property=\"og:description\" content=\"I migliori segnapunti elettronici e tariffatori per campi da bocce. Indispensabili per diputare gare e tornei. Necessari per contabilizzare le ore di gioco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/\" \/>\n<meta property=\"og:site_name\" content=\"Colleoni Bocce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/categoria-prodotto\\\/segnapunti-e-tariffatori\\\/\",\"url\":\"https:\\\/\\\/colleonibocce.com\\\/categoria-prodotto\\\/segnapunti-e-tariffatori\\\/\",\"name\":\"Segnapunti elettronici e tariffatori per campi da bocce - Colleoni bocce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/#website\"},\"description\":\"I migliori segnapunti elettronici e tariffatori per campi da bocce. Indispensabili per diputare gare e tornei. Necessari per contabilizzare le ore di gioco.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/categoria-prodotto\\\/segnapunti-e-tariffatori\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/categoria-prodotto\\\/segnapunti-e-tariffatori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/colleonibocce.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segnapunti e tariffatori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/#website\",\"url\":\"https:\\\/\\\/colleonibocce.com\\\/\",\"name\":\"Colleoni Bocce\",\"description\":\"Campi da bocce - Impianti sportivi\",\"publisher\":{\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/colleonibocce.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/#organization\",\"name\":\"Colleoni Bocce\",\"url\":\"https:\\\/\\\/colleonibocce.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/colleonibocce.com\\\/content\\\/uploads\\\/2018\\\/03\\\/cropped-placeholder_colleoni.jpg\",\"contentUrl\":\"https:\\\/\\\/colleonibocce.com\\\/content\\\/uploads\\\/2018\\\/03\\\/cropped-placeholder_colleoni.jpg\",\"width\":290,\"height\":48,\"caption\":\"Colleoni Bocce\"},\"image\":{\"@id\":\"https:\\\/\\\/colleonibocce.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segnapunti elettronici e tariffatori per campi da bocce - Colleoni bocce","description":"I migliori segnapunti elettronici e tariffatori per campi da bocce. Indispensabili per diputare gare e tornei. Necessari per contabilizzare le ore di gioco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/","og_locale":"en_US","og_type":"article","og_title":"Segnapunti elettronici e tariffatori per campi da bocce - Colleoni bocce","og_description":"I migliori segnapunti elettronici e tariffatori per campi da bocce. Indispensabili per diputare gare e tornei. Necessari per contabilizzare le ore di gioco.","og_url":"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/","og_site_name":"Colleoni Bocce","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/","url":"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/","name":"Segnapunti elettronici e tariffatori per campi da bocce - Colleoni bocce","isPartOf":{"@id":"https:\/\/colleonibocce.com\/#website"},"description":"I migliori segnapunti elettronici e tariffatori per campi da bocce. Indispensabili per diputare gare e tornei. Necessari per contabilizzare le ore di gioco.","breadcrumb":{"@id":"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/colleonibocce.com\/categoria-prodotto\/segnapunti-e-tariffatori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/colleonibocce.com\/en\/"},{"@type":"ListItem","position":2,"name":"Segnapunti e tariffatori"}]},{"@type":"WebSite","@id":"https:\/\/colleonibocce.com\/#website","url":"https:\/\/colleonibocce.com\/","name":"Colleoni Bocce","description":"Campi da bocce - Impianti sportivi","publisher":{"@id":"https:\/\/colleonibocce.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/colleonibocce.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/colleonibocce.com\/#organization","name":"Colleoni Bocce","url":"https:\/\/colleonibocce.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/colleonibocce.com\/#\/schema\/logo\/image\/","url":"https:\/\/colleonibocce.com\/content\/uploads\/2018\/03\/cropped-placeholder_colleoni.jpg","contentUrl":"https:\/\/colleonibocce.com\/content\/uploads\/2018\/03\/cropped-placeholder_colleoni.jpg","width":290,"height":48,"caption":"Colleoni Bocce"},"image":{"@id":"https:\/\/colleonibocce.com\/#\/schema\/logo\/image\/"}}]}},"cat_url":"https:\/\/colleonibocce.com\/en\/product-category\/scoreboard-and-timer-counters\/","_links":{"self":[{"href":"https:\/\/colleonibocce.com\/en\/wp-json\/wp\/v2\/product_cat\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colleonibocce.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/colleonibocce.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/colleonibocce.com\/en\/wp-json\/wp\/v2\/product?product_cat=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}